{"id":1957,"date":"2024-04-30T14:17:11","date_gmt":"2024-04-30T14:17:11","guid":{"rendered":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/"},"modified":"2024-04-30T14:17:11","modified_gmt":"2024-04-30T14:17:11","slug":"cookie-policy-eu","status":"publish","type":"page","link":"https:\/\/www.zjjiangtian.com\/es\/politica-de-cookies-de-la-ue\/","title":{"rendered":"Pol\u00edtica de cookies (UE)"},"content":{"rendered":"<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta Pol\u00edtica de cookies fue actualizada por \u00faltima vez el 2025-12-22 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br><\/p><h2>1. Introducci\u00f3n<\/h2><p>Nuestra web, <a href=\"https:\/\/www.zjjiangtian.com\/es\">https:\/\/www.zjjiangtian.com\/es<\/a> (en adelante: &quot;la web&quot;) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominar\u00e1n como &quot;cookies&quot;). Las cookies tambi\u00e9n pueden ser colocadas por terceros que hemos contratado. En el siguiente documento le informamos sobre el uso de cookies en nuestra web.<\/p><h2>2. \u00bfQu\u00e9 son las cookies?<\/h2><p>Una cookie es un peque\u00f1o archivo que se env\u00eda junto con las p\u00e1ginas de esta web y que su navegador almacena en el disco duro de su ordenador u otro dispositivo. La informaci\u00f3n almacenada puede ser devuelta a nuestros servidores oa los servidores de terceros apropiados durante una visita posterior.<\/p><h2>3. \u00bfQu\u00e9 son los scripts?<\/h2><p>Un script es un fragmento de c\u00f3digo de programa que se utiliza para hacer que nuestra web funcione correctamente y de forma interactiva. Este c\u00f3digo se ejecuta en nuestro servidor o en su dispositivo.<\/p><h2>4. \u00bfQu\u00e9 es una baliza web?<\/h2><p>Una baliza web (o una etiqueta de p\u00edxel) es una peque\u00f1a e invisible pieza de texto o imagen en una web que se utiliza para monitorear el tr\u00e1fico en una web. Para ello, se almacenan varios datos sobre usted mediante estas balizas web.<\/p><h2>5. Galletas<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies t\u00e9cnicas o funcionales<\/p><p>Algunas cookies aseguran que ciertas partes de la web funcionen correctamente y que sus preferencias de usuario sigan siendo reconocidas. Al colocar cookies funcionales, le facilitamos la visita a nuestra web. De esta manera, usted no necesita introducir repetidamente la misma informaci\u00f3n cuando visite nuestra web y, por ejemplo, los art\u00edculos permanecer\u00e1n en su cesta de la compra hasta que usted haya pagado. Podemos colocar estas cookies sin su consentimiento.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies de estad\u00edsticas<\/p><p>Utilizamos cookies estad\u00edsticas para optimizar la experiencia de la web para nuestros usuarios. Con estas estad\u00edsticas de cookies obtenemos informaci\u00f3n sobre el uso de nuestra web. Le pedimos su permiso para colocar estad\u00edsticas de cookies.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de Marketing\/Seguimiento<\/p><p>Las cookies de marketing\/seguimiento son cookies, o cualquier otra forma de almacenamiento local, usadas para crear perfiles de usuario para mostrar publicidad o para hacer el seguimiento del usuario en esta web o en varias webs con fines de marketing similares.<\/p><h2>6. Cookies utilizadas<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Estad\u00edsticas (an\u00f3nimas)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio Elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Elementor para creaci\u00f3n de contenido. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas (an\u00f3nimas)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elemento<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar acciones hechas por usuarios en el sitio web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WordPress para desarrollo de sitios web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsCompatible<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">configuraci\u00f3n wp-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar las preferencias de los usuarios<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-configuraciones-tiempo-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar las preferencias de los usuarios<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">cookie de prueba de wordpress<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Compruebe si se pueden instalar cookies<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_iniciado_sesi\u00f3n_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Mantener los usuarios registrados<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Anuncios de Google<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-adsense\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio de Google Adsense<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-adsense\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-adsense\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Adsense para mostrar anuncios. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-adsense\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Pol\u00edtica de privacidad de Google Adsense<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/_gcl_au\/\">_gcl_au<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar y realizar un seguimiento de las conversiones<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">configuraci\u00f3n de google adsense<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>An\u00e1lisis de Google<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio Google Analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Analytics para estad\u00edsticas del sitio web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Pol\u00edtica de privacidad de Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_Georgia<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">2 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_Georgia_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Contar y rastrear p\u00e1ginas vistas<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Claridad de Microsoft<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_microsoft-clarity\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio microsoft-clarity<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_microsoft-clarity\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"microsoft-clarity\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Microsoft Clarity para mapas con zonas calientes y grabaci\u00f3n de pantalla. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/microsoft\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/privacy.microsoft.com\/en-us\/privacystatement\">Microsoft Clarity Pol\u00edtica de privacidad<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/microsoft\/_clck\/\">_clic<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">AN\u00d3NIMO<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">MUIDO<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Formularios WP<\/h3>\n\t\t<p>Preferencias<\/p>\n\t\t<label for=\"cmplz_service_wpforms\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio wpforms<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpforms\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpforms\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WPForms para formularios web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpforms\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Preferencias<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpforms\/_wpfuuid\/\">_wpfuuid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">11 a\u00f1os<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Almacenar un ID de usuario \u00fanico<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Fuente de JavaScript de Sourcebuster<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_sourcebuster-js\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio sourcebuster-js<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sourcebuster-js\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sourcebuster-js\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Sourcebuster JS para seguimiento de visitantes. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/sourcebuster-js\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_migrations\/\">migraciones sbjs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first_add\/\">sbjs_primera_adici\u00f3n<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_current\/\">sbjs_actual<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first\/\">sbjs_primero<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_session\/\">sesi\u00f3n sbjs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Fuentes de Google<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Fonts para mostrar fuentes web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Pol\u00edtica de privacidad de Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">API de fuentes de Google<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio de YouTube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos YouTube para mostrar v\u00eddeo. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Leer m\u00e1s<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Pol\u00edtica de privacidad de YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">INFORMACI\u00d3N_DE_VISITANTE1_EN_VIVO<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">PREFERENCIA<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Miscel\u00e1neas<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_miscel\u00e1neas\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentimiento para el servicio de miscel\u00e1neas<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_miscel\u00e1neas\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"miscel\u00e1neas\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_current_add\/\">sbjs_actual_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_udata\/\">Datos sbjs_udata<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">6 meses<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_wpfuj<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">nivel de registro<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">datos_de_usuario_cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">persistir:hs-beacon-1ae02e91-5865-4f13-b220-7daed946ba25<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">e_globales<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Id. del trabajo en proceso<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">persistir:hs-beacon-mensaje-1ae02e91-5865-4f13-b220-7daed946ba25<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Valores predeterminados de elementos e_kit<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">estado del banner de cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">servicios consentidos por cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">id_de_pol\u00edtica_cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">marketing_cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">estad\u00edsticas_cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">preferencias_cmplz<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_funcional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ca04e1a769d6e87b84fd6bcda0639ce1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ee39232f299f5f2111af5a60d5d10fd1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">6cb1f90cba489c85caa3c2ee6ebd0ccc<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_cltk<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_cerrar<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">WP_DATOS_USUARIO_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">biblioteca electr\u00f3nica<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">tiendaApiNonce<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">clave de valor extendida<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">mover-x<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Mu\u00e9vete<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">clic-x<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">clic-y<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_gcl_ls<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimiento<\/h2><p>Cuando visite nuestra web por primera vez, le mostraremos una ventana emergente con una explicaci\u00f3n sobre las cookies. En cuanto haga clic en &quot;Guardar preferencias&quot;, le dar\u00e1 su consentimiento para que utilicemos las categor\u00edas de cookies y complementos que haya seleccionado en la ventana emergente, tal y como se describe en esta Pol\u00edtica de cookies. Puede desactivar el uso de cookies a trav\u00e9s de su navegador, pero tenga en cuenta que nuestra web podr\u00eda dejar de funcionar correctamente.<\/p><p class=\"cmplz-subtitle\">7.1 Administrar sus ajustes de consentimiento<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Ha cargado la Pol\u00edtica de cookies sin soporte de javascript. En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3n\/desactivaci\u00f3n y eliminaci\u00f3n de cookies<\/h2><p>Puede utilizar su navegador de internet para eliminar las cookies autom\u00e1tica o manualmente. Tambi\u00e9n puede especificar que no se coloquen determinadas cookies. Otra opci\u00f3n es cambiar los ajustes de su navegador de internet para que reciba un mensaje cada vez que se coloque una cookie. Para obtener m\u00e1s informaci\u00f3n sobre estas opciones, consulte las instrucciones de la secci\u00f3n de ayuda de su navegador.<\/p><p>Ten en cuenta que nuestro sitio web puede no funcionar correctamente si se deshabilitan todas las cookies. Si decide eliminar las cookies de su navegador, se volver\u00e1n a colocar despu\u00e9s de que des su consentimiento la pr\u00f3xima vez que visite nuestro sitio web.<\/p><h2>9. Sus derechos con respecto a los datos personales<\/h2><p>Usted tiene los siguientes derechos con respecto a sus datos personales:<\/p><ul>\n                    <li>Usted tiene derecho a saber por qu\u00e9 se necesitan sus datos personales, qu\u00e9 pasar\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                    <li>Derecho de acceso: Tiene derecho a acceder a los datos personales que conocemos sobre usted.<\/li>\n                    <li>Derecho de rectificaci\u00f3n: tiene derecho a completar, rectificar, borrar o bloquear sus datos personales cuando lo desee.<\/li>\n                    <li>Si usted nos da su consentimiento para procesar sus datos, tiene derecho a revocar dicho consentimiento ya que se eliminan sus datos personales.<\/li>\n                    <li>Derecho de cesi\u00f3n de sus datos: tiene derecho a solicitar todos sus datos personales al responsable y transferirlos \u00edntegramente a otro responsable del tratamiento de datos.<\/li>\n                    <li>Derecho de oposici\u00f3n: usted puede oponerse al tratamiento de sus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el tratamiento.<\/li>\n                <\/ul><p>Para ejercer estos derechos, por favor, p\u00f3ngase en contacto con nosotros. Por favor refi\u00e9rase a los detalles de contacto en la parte inferior de esta Pol\u00edtica de dookies. Si tiene alguna queja sobre c\u00f3mo manejamos sus datos, nos gustar\u00eda que nos lo indiquen, no obstante, tambi\u00e9n tiene derecho a presentar una reclamaci\u00f3n a la autoridad supervisora (la Autoridad de protecci\u00f3n de datos).<\/p><h2>10. Datos de contacto<\/h2><p>Para preguntas y\/o comentarios sobre nuestra Pol\u00edtica de cookies y esta declaraci\u00f3n, p\u00f3ngase en contacto con nosotros utilizando los siguientes datos de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">Jiangtian M\u00e1quina El\u00e9ctrica Co., Ltd.<\/span><br>\n                      <span class=\"cmplz-contact-address\">Ciudad de Yangbu, distrito de Wucheng, ciudad de Jinha, provincia de Zhejiang<\/span><br>\n                      <span class=\"cmplz-contact-country\">Porcelana<\/span><br>\n                    Web: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/www.zjjiangtian.com\/es\">https:\/\/www.zjjiangtian.com\/es<\/a><\/span><br>\n                    Correo electr\u00f3nico: <span class=\"cmplz-contact-email\">&#115;&#097;&#108;&#101;s&#064;zj&#106;&#105;angti&#097;n&#046;c&#111;&#109;<\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Esta Politica de cookies se sincroniz\u00f3 con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">basededatosdecookies.org<\/a> el 2026-07-14.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v22.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cookie Policy (EU) - Jiangtian Electric<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zjjiangtian.com\/es\/politica-de-cookies-de-la-ue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy (EU)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zjjiangtian.com\/es\/politica-de-cookies-de-la-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Jiangtian Electric\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\",\"url\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\",\"name\":\"Cookie Policy (EU) - Jiangtian Electric\",\"isPartOf\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#website\"},\"datePublished\":\"2024-04-30T14:17:11+00:00\",\"dateModified\":\"2024-04-30T14:17:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.zjjiangtian.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy (EU)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#website\",\"url\":\"https:\/\/www.zjjiangtian.com\/\",\"name\":\"Jiangtian Electric\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zjjiangtian.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#organization\",\"name\":\"Jiangtian Electric\",\"url\":\"https:\/\/www.zjjiangtian.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp\",\"contentUrl\":\"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp\",\"width\":269,\"height\":50,\"caption\":\"Jiangtian Electric\"},\"image\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cookie Policy (EU) - Jiangtian Electric","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zjjiangtian.com\/es\/politica-de-cookies-de-la-ue\/","og_locale":"es_ES","og_type":"article","og_title":"Cookie Policy (EU)","og_url":"https:\/\/www.zjjiangtian.com\/es\/politica-de-cookies-de-la-ue\/","og_site_name":"Jiangtian Electric","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/","url":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/","name":"Cookie Policy (EU) - Jiangtian Electric","isPartOf":{"@id":"https:\/\/www.zjjiangtian.com\/#website"},"datePublished":"2024-04-30T14:17:11+00:00","dateModified":"2024-04-30T14:17:11+00:00","breadcrumb":{"@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zjjiangtian.com\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy (EU)"}]},{"@type":"WebSite","@id":"https:\/\/www.zjjiangtian.com\/#website","url":"https:\/\/www.zjjiangtian.com\/","name":"Jiangtian Electric","description":"","publisher":{"@id":"https:\/\/www.zjjiangtian.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zjjiangtian.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zjjiangtian.com\/#organization","name":"Jiangtian Electric","url":"https:\/\/www.zjjiangtian.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp","contentUrl":"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp","width":269,"height":50,"caption":"Jiangtian Electric"},"image":{"@id":"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/pages\/1957"}],"collection":[{"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/comments?post=1957"}],"version-history":[{"count":0,"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/pages\/1957\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zjjiangtian.com\/es\/wp-json\/wp\/v2\/media?parent=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}