{"id":1957,"date":"2024-04-30T14:17:11","date_gmt":"2024-04-30T14:17:11","guid":{"rendered":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/"},"modified":"2024-04-30T14:17:11","modified_gmt":"2024-04-30T14:17:11","slug":"cookie-policy-eu","status":"publish","type":"page","link":"https:\/\/www.zjjiangtian.com\/fr\/politique-de-cookies-de-lue\/","title":{"rendered":"Politique de cookies (UE)"},"content":{"rendered":"<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le 2025-12-22 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00c9conomique Europ\u00e9en et de la Suisse.<\/i><br><\/p><h2>1. Introduction<\/h2><p>Notre site web, <a href=\"https:\/\/www.zjjiangtian.com\/fr\">https:\/\/www.zjjiangtian.com\/fr<\/a> (ci-apr\u00e8s : \u00ab le site web \u00bb) utilise des cookies et autres technologies li\u00e9es (par simplification, toutes ces technologies sont d\u00e9sign\u00e9es par le terme \u00ab cookies \u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tierces parties que nous avons engag\u00e9es. Dans le document ci-dessous, nous vous informons de l&#039;utilisation des cookies sur notre site web.<\/p><h2>2. Que sont les cookies ?<\/h2><p>Un cookie est un petit fichier simple envoy\u00e9 avec les pages de ce site web et stock\u00e9 par votre navigateur sur le disque dur de votre ordinateur ou d&#039;un autre appareil. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs ou aux serveurs des tierces parties concern\u00e9es lors d&#039;une visite ult\u00e9rieure.<\/p><h2>3. Que sont les scripts ?<\/h2><p>Un script est un \u00e9l\u00e9ment de code utilis\u00e9 pour que notre site web fonctionne correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p><h2>4. Qu&#039;est-ce qu&#039;une balise invisible ?<\/h2><p>Une balise invisible (ou balise web) est un petit morceau de texte ou d&#039;image invisible sur un site web, utilis\u00e9 pour suivre le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l&#039;aide de balises invisibles.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies techniques ou fonctionnels<\/p><p>Certains cookies assurent le fonctionnement correct de certaines parties du site web et la prise en compte de vos pr\u00e9f\u00e9rences en tant qu&#039;utilisateur. En fournissant des cookies fonctionnels, nous vous facilitons la visite de notre site web. Ainsi, vous n&#039;avez pas besoin de saisir \u00e0 plusieurs reprises les m\u00eames informations lors de la visite de notre site web et, par exemple, les \u00e9l\u00e9ments restent dans votre panier jusqu&#039;\u00e0 votre paiement. Nous pouvons placer ces cookies sans votre consentement.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies statistiques<\/p><p>Nous utilisons des cookies statistiques afin d&#039;optimiser l&#039;exp\u00e9rience des internautes sur notre site web. Avec ces cookies statistiques, nous obtenons des informations sur l&#039;utilisation de notre site web. Nous demandons votre autorisation pour placer des cookies statistiques.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de marketing\/suivi<\/p><p>Les cookies de marketing\/suivi sont des cookies ou toute autre forme de stockage local, utilis\u00e9s pour cr\u00e9er des profils d&#039;utilisateurs afin d&#039;afficher de la publicit\u00e9 ou de suivre l&#039;utilisateur sur ce site web ou sur plusieurs sites web dans des finalit\u00e9s. marketing similaire.<\/p><h2>6. Cookies plac\u00e9s<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>\u00c9l\u00e9mentor<\/h3>\n\t\t<p>Statistiques (anonymes)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement \u00e0 l&#039;\u00e9l\u00e9ment de service<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Elementor pour la cr\u00e9ation de contenu. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques (anonymes)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">\u00e9l\u00e9mentor<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistant<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les actions effectu\u00e9es par les utilisateurs sur le site web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Fonctionnel<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service WordPress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WordPress pour le d\u00e9veloppement du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Fonctionnel<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsPrend en charge<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les informations du navigateur<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">param\u00e8tres-wp-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistant<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-heure-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les pr\u00e9f\u00e9rences des utilisateurs<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">test_cookie_wordpress<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">V\u00e9rifier si les cookies peuvent \u00eatre d\u00e9pos\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_connect\u00e9_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistant<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Garder les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Adsense<\/h3>\n\t\t<p>Commercialisation<\/p>\n\t\t<label for=\"cmplz_service_google-adsense\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service Google Adsense<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-adsense\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-adsense\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Adsense pour l&#039;affichage de publicit\u00e9s. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-adsense\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d&#039;informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Adsense<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Commercialisation<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/_gcl_au\/\">_gcl_au<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistant<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker et suivre les conversions<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">param\u00e8tres_google_adsense<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistiques<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service Google Analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Analytics pour les statistiques du site web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d&#039;informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_G\u00e9orgie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">2 ans<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Compter et suivre les pages visit\u00e9es<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_G\u00e9orgie_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Compter et suivre les pages visit\u00e9es<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Clart\u00e9 de Microsoft<\/h3>\n\t\t<p>Commercialisation<\/p>\n\t\t<label for=\"cmplz_service_microsoft-clarity\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service Microsoft-Clarity<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_microsoft-clarity\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"microsoft-clarity\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Microsoft Clarity pour les cartes de fr\u00e9quentation (heat maps) et les enregistrements d&#039;\u00e9cran. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/microsoft\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d&#039;informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/privacy.microsoft.com\/en-us\/privacystatement\">d\u00e9claration de confidentialit\u00e9 Microsoft Clarity<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Commercialisation<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/microsoft\/_clck\/\">_clic<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 an<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker un identifiant utilisateur unique<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ANONCHK<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">MUID<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Formulaires WP<\/h3>\n\t\t<p>Pr\u00e9f\u00e9rences<\/p>\n\t\t<label for=\"cmplz_service_wpforms\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service wpforms<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpforms\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpforms\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WPForms pour les formulaires web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpforms\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pr\u00e9f\u00e9rences<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpforms\/_wpfuuid\/\">_wpfuuid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">11 ans<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker un identifiant utilisateur unique<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sourcebuster JS<\/h3>\n\t\t<p>Statistiques<\/p>\n\t\t<label for=\"cmplz_service_sourcebuster-js\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service sourcebuster-js<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sourcebuster-js\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sourcebuster-js\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Sourcebuster JS pour le suivi des visiteurs. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/sourcebuster-js\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_migrations\/\">migrations_sbjs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first_add\/\">sbjs_first_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_current\/\">sbjs_current<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">Stocker les informations du navigateur<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_first\/\">sbjs_first<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/sourcebuster-js\/sbjs_session\/\">session_sbjs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Polices Google<\/h3>\n\t\t<p>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service Google Fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Fonts pour l&#039;affichage des politiques web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d&#039;informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">API des polices Google<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement au service YouTube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons YouTube pour l&#039;affichage de vid\u00e9os. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Lire la suite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d&#039;informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">INFO_VISITEUR1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">PR\u00c9F<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Plongeurs<\/h3>\n\t\t<p>Statistiques<\/p>\n\t\t<label for=\"cmplz_service_divers\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consentement aux plongeurs de service<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divers\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divers\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Le partage des donn\u00e9es est en cours d&#039;enqu\u00eate<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_current_add\/\">sbjs_current_add<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/sbjs_udata\/\">sbjs_udata<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">6 mois<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d&#039;enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_wpfuj<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">niveau de log<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_user_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">persister\u00a0:\u00a0hs-beacon-1ae02e91-5865-4f13-b220-7daed946ba25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_globals<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ID de la t\u00e2che en cours de traitement<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">persister\u00a0:\u00a0hs-beacon-message-1ae02e91-5865-4f13-b220-7daed946ba25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_kit-\u00e9l\u00e9ments-par-d\u00e9faut<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-statut<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistiques<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_fonctionnel<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ca04e1a769d6e87b84fd6bcda0639ce1<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ee39232f299f5f2111af5a60d5d10fd1<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">6cb1f90cba489c85caa3c2ee6ebd0ccc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_cltk<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_clsk<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Biblioth\u00e8que \u00e9lectronique<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">magasinApiNonce<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cl\u00e9 de valeur \u00e9tendue<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">d\u00e9placer-x<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">bouge-y<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cliquez-x<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">clic-y<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_gcl_ls<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentement<\/h2><p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous vous montrons une fen\u00eatre contextuelle avec une explication sur les cookies. D\u00e8s que vous cliquez sur \u00ab Enregistrer les pr\u00e9f\u00e9rences \u00bb vous nous autorisez \u00e0 utiliser les cat\u00e9gories de cookies et d&#039;extensions que vous avez s\u00e9lectionn\u00e9es dans la fen\u00eatre contextuelle, comme d\u00e9crit dans la pr\u00e9sente politique de cookies. Vous pouvez d\u00e9sactiver l&#039;utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement.<\/p><p class=\"cmplz-subtitle\">7.1 G\u00e9rez vos r\u00e9glages de consentement<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Vous avez charg\u00e9 la politique de cookies sans le support de javascript. Sur AMP, vous pouvez utiliser l&#039;onglet de gestion du consentement en bas de la page.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activer\/d\u00e9sactiver et supprimer les cookies<\/h2><p>Vous pouvez utiliser votre navigateur internet pour supprimer automatiquement ou manuellement les cookies. Vous pouvez \u00e9galement pr\u00e9ciser que certains cookies ne peuvent pas \u00eatre plac\u00e9s. Une autre option consiste \u00e0 modifier les param\u00e8tres de votre navigateur Internet afin que vous receviez un message \u00e0 chaque fois qu&#039;un cookie est plac\u00e9. Pour plus d&#039;informations sur ces options, reportez-vous aux instructions de la section Aide de votre navigateur.<\/p><p>Veuillez noter que notre site Web peut ne pas marcher correctement si tous les cookies sont d\u00e9sactiv\u00e9s. Si vous supprimez les cookies dans votre navigateur, ils seront de nouveau plac\u00e9s apr\u00e8s votre consentement lorsque vous revisiterez notre site web.<\/p><h2>9. Vos droits concernant les donn\u00e9es personnelles<\/h2><p>Vous avez les droits suivants concernant vos donn\u00e9es personnelles :<\/p><ul>\n                    <li>Vous avez le droit de savoir pourquoi vos donn\u00e9es personnelles sont n\u00e9cessaires, ce qui leur arrivent et combien de temps elles seront conserv\u00e9es.<\/li>\n                    <li>Droit d&#039;acc\u00e8s : vous avez le droit d&#039;acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous connaissons.<\/li>\n                    <li>Droit de rectification : vous avez le droit \u00e0 tout moment de compl\u00e9ter, corriger, faire supprimer ou bloquer vos donn\u00e9es personnelles.<\/li>\n                    <li>Si vous nous donnez votre consentement pour le traitement de vos donn\u00e9es, vous avez le droit de r\u00e9voquer ce consentement et de faire supprimer vos donn\u00e9es personnelles.<\/li>\n                    <li>Droit de transf\u00e9rer vos donn\u00e9es : vous avez le droit de demander toutes vos donn\u00e9es personnelles au responsable du traitement et de les transf\u00e9rer dans leur int\u00e9gralit\u00e9 \u00e0 un autre responsable du traitement.<\/li>\n                    <li>Droit d&#039;opposition : vous pouvez vous opposer au traitement de vos donn\u00e9es. Nous obtemp\u00e9rerons, \u00e0 moins que certaines raisons ne justifient ce traitement.<\/li>\n                <\/ul><p>Pour exercer ces droits, veuillez nous contacter. Veuillez vous identifier aux coordonn\u00e9es au bas de cette politique de cookies. Si vous avez une plainte concernant la fa\u00e7on dont nous traitons vos donn\u00e9es, nous aimerions en \u00eatre inform\u00e9s, mais vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l&#039;autorit\u00e9 de contr\u00f4le (l&#039;autorit\u00e9 charg\u00e9e de la protection des donn\u00e9es).<\/p><h2>10. Coordonn\u00e9es<\/h2><p>Pour des questions et\/ou des commentaires sur notre politique de cookies et cette d\u00e9claration, veuillez nous contacter en utilisant les coordonn\u00e9es suivantes :<\/p><p><span class=\"cmplz-contact-organisation\">Jiangtian Electric Machine Co., Ltd.<\/span><br>\n                      <span class=\"cmplz-contact-address\">Ville de Yangbu, district de Wucheng, ville de Jinha, province du Zhejiang<\/span><br>\n                      <span class=\"cmplz-contact-country\">\u00c9chine<\/span><br>\n                    Site web : <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/www.zjjiangtian.com\/fr\">https:\/\/www.zjjiangtian.com\/fr<\/a><\/span><br>\n                    E-mail : <span class=\"cmplz-contact-email\">&#115;a&#108;e&#115;&#064;z&#106;&#106;&#105;&#097;ng&#116;i&#097;&#110;&#046;&#099;om<\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Cette politique de cookies a \u00e9t\u00e9 synchronis\u00e9e avec <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> le 2026-07-14.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v22.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cookie Policy (EU) - Jiangtian Electric<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zjjiangtian.com\/fr\/politique-de-cookies-de-lue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy (EU)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zjjiangtian.com\/fr\/politique-de-cookies-de-lue\/\" \/>\n<meta property=\"og:site_name\" content=\"Jiangtian Electric\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\",\"url\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\",\"name\":\"Cookie Policy (EU) - Jiangtian Electric\",\"isPartOf\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#website\"},\"datePublished\":\"2024-04-30T14:17:11+00:00\",\"dateModified\":\"2024-04-30T14:17:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.zjjiangtian.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy (EU)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#website\",\"url\":\"https:\/\/www.zjjiangtian.com\/\",\"name\":\"Jiangtian Electric\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zjjiangtian.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#organization\",\"name\":\"Jiangtian Electric\",\"url\":\"https:\/\/www.zjjiangtian.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp\",\"contentUrl\":\"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp\",\"width\":269,\"height\":50,\"caption\":\"Jiangtian Electric\"},\"image\":{\"@id\":\"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cookie Policy (EU) - Jiangtian Electric","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zjjiangtian.com\/fr\/politique-de-cookies-de-lue\/","og_locale":"fr_FR","og_type":"article","og_title":"Cookie Policy (EU)","og_url":"https:\/\/www.zjjiangtian.com\/fr\/politique-de-cookies-de-lue\/","og_site_name":"Jiangtian Electric","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/","url":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/","name":"Cookie Policy (EU) - Jiangtian Electric","isPartOf":{"@id":"https:\/\/www.zjjiangtian.com\/#website"},"datePublished":"2024-04-30T14:17:11+00:00","dateModified":"2024-04-30T14:17:11+00:00","breadcrumb":{"@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zjjiangtian.com\/cookie-policy-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zjjiangtian.com\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy (EU)"}]},{"@type":"WebSite","@id":"https:\/\/www.zjjiangtian.com\/#website","url":"https:\/\/www.zjjiangtian.com\/","name":"Jiangtian Electric","description":"","publisher":{"@id":"https:\/\/www.zjjiangtian.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zjjiangtian.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.zjjiangtian.com\/#organization","name":"Jiangtian Electric","url":"https:\/\/www.zjjiangtian.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp","contentUrl":"https:\/\/www.zjjiangtian.com\/wp-content\/uploads\/2023\/10\/logo.webp","width":269,"height":50,"caption":"Jiangtian Electric"},"image":{"@id":"https:\/\/www.zjjiangtian.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/pages\/1957"}],"collection":[{"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/comments?post=1957"}],"version-history":[{"count":0,"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/pages\/1957\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zjjiangtian.com\/fr\/wp-json\/wp\/v2\/media?parent=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}